{"id":36459,"date":"2023-06-11T14:13:11","date_gmt":"2023-06-11T12:13:11","guid":{"rendered":"https:\/\/www.uds-parts.com\/?post_type=product&#038;p=36459"},"modified":"2026-05-13T10:29:22","modified_gmt":"2026-05-13T08:29:22","slug":"achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5","status":"publish","type":"product","link":"https:\/\/uds-parts.com\/en\/producten\/lighting\/rear-lights\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/","title":{"rendered":"Achterlicht &#8220;RIO&#8221; LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm"},"content":{"rendered":"<p>Ingebouwde knipperlicht verklikker! | Kentekenverlichting aan zijkant als optie mogelijk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingebouwde knipperlicht verklikker! | Kentekenverlichting aan zijkant als optie mogelijk<\/p>\n","protected":false},"featured_media":52679,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false},"product_brand":[],"product_cat":[342,6524],"product_tag":[],"class_list":{"0":"post-36459","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-verlichting-led-verlichting","7":"product_cat-achterlichten","8":"pa_maat-152mm","9":"pa_merk-sanube","10":"pa_type-2-led","11":"pa_verkoop-eenheid-stuk","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Achterlicht &quot;RIO&quot; LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Achterlicht &quot;RIO&quot; LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts\" \/>\n<meta property=\"og:description\" content=\"Ingebouwde knipperlicht verklikker! | Kentekenverlichting aan zijkant als optie mogelijk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/\" \/>\n<meta property=\"og:site_name\" content=\"UDS Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uds-parts.com\/wp-content\/uploads\/sanube-rio-111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"378\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;171,73\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/\",\"name\":\"Achterlicht \\\"RIO\\\" LED | LINKS | 12V \\\/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/sanube-rio-111.jpg\",\"datePublished\":\"2023-06-11T12:13:11+00:00\",\"dateModified\":\"2026-05-13T08:29:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/sanube-rio-111.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/sanube-rio-111.jpg\",\"width\":378,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/achterlichten\\\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/en\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verlichting\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/product-categorie\\\/verlichting-led-verlichting\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Achterlichten\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/product-categorie\\\/verlichting-led-verlichting\\\/achterlichten\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Achterlicht &#8220;RIO&#8221; LED | LINKS | 12V \\\/ met 200 mm kabel | 4 functies Sanube 152mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"name\":\"United Driveline Systems\",\"description\":\"United Driveline Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\"},\"alternateName\":\"UDS Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uds-parts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\",\"name\":\"United Driveline Systems b.v.\",\"alternateName\":\"UDS Parts\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"width\":803,\"height\":342,\"caption\":\"United Driveline Systems b.v.\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/uds_parts\\\/\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/united-driveline-systems-bv\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"SANUBE\" \/>\n<meta property=\"product:price:amount\" content=\"171.73\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"7-3H3156-072\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Achterlicht \"RIO\" LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/","og_locale":"en_US","og_type":"article","og_title":"Achterlicht \"RIO\" LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts","og_description":"Ingebouwde knipperlicht verklikker! | Kentekenverlichting aan zijkant als optie mogelijk","og_url":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/","og_site_name":"UDS Parts","article_modified_time":"2026-05-13T08:29:22+00:00","og_image":[{"width":378,"height":378,"url":"https:\/\/uds-parts.com\/wp-content\/uploads\/sanube-rio-111.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;171,73","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/","url":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/","name":"Achterlicht \"RIO\" LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm - UDS Parts","isPartOf":{"@id":"https:\/\/uds-parts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/#primaryimage"},"image":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/#primaryimage"},"thumbnailUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/sanube-rio-111.jpg","datePublished":"2023-06-11T12:13:11+00:00","dateModified":"2026-05-13T08:29:22+00:00","breadcrumb":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/#primaryimage","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/sanube-rio-111.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/sanube-rio-111.jpg","width":378,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/achterlichten\/achterlicht-rio-led-links-12v-met-200-mm-kabel-4-functies-sanube-152mm-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uds-parts.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/uds-parts.com\/en\/webshop\/"},{"@type":"ListItem","position":3,"name":"Verlichting","item":"https:\/\/uds-parts.com\/product-categorie\/verlichting-led-verlichting\/"},{"@type":"ListItem","position":4,"name":"Achterlichten","item":"https:\/\/uds-parts.com\/product-categorie\/verlichting-led-verlichting\/achterlichten\/"},{"@type":"ListItem","position":5,"name":"Achterlicht &#8220;RIO&#8221; LED | LINKS | 12V \/ met 200 mm kabel | 4 functies Sanube 152mm"}]},{"@type":"WebSite","@id":"https:\/\/uds-parts.com\/#website","url":"https:\/\/uds-parts.com\/","name":"United Driveline Systems","description":"United Driveline Systems","publisher":{"@id":"https:\/\/uds-parts.com\/#organization"},"alternateName":"UDS Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uds-parts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uds-parts.com\/#organization","name":"United Driveline Systems b.v.","alternateName":"UDS Parts","url":"https:\/\/uds-parts.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","width":803,"height":342,"caption":"United Driveline Systems b.v."},"image":{"@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/uds_parts\/","https:\/\/nl.linkedin.com\/company\/united-driveline-systems-bv"]}]},"product_brand":"SANUBE","product_price_amount":"171.73","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"7-3H3156-072","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/product\/36459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/media\/52679"}],"wp:attachment":[{"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/media?parent=36459"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/product_brand?post=36459"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/product_cat?post=36459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/uds-parts.com\/en\/wp-json\/wp\/v2\/product_tag?post=36459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}