{"id":30301,"date":"2023-06-11T13:59:48","date_gmt":"2023-06-11T11:59:48","guid":{"rendered":"https:\/\/www.uds-parts.com\/producten\/uncategorized\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/"},"modified":"2026-08-10T09:41:44","modified_gmt":"2026-08-10T07:41:44","slug":"led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting","status":"publish","type":"product","link":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/arbeitsscheinwerfer\/led-de\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/","title":{"rendered":"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting"},"content":{"rendered":"<p>Afdichtingsklasse IP67-IP69K<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afdichtingsklasse IP67-IP69K<\/p>\n","protected":false},"featured_media":30283,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false},"product_brand":[],"product_cat":[342,547,6635],"product_tag":[],"class_list":["post-30301","product","type-product","status-publish","has-post-thumbnail","product_cat-verlichting-led-verlichting","product_cat-werklampen","product_cat-led","pa_maat-100x100","pa_merk-wesem","pa_type-2-led","pa_type-2-deutsch-conn","pa_verkoop-eenheid-stuk","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts\" \/>\n<meta property=\"og:description\" content=\"Afdichtingsklasse IP67-IP69K\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/\" \/>\n<meta property=\"og:site_name\" content=\"UDS Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-10T07:41:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uds-parts.com\/wp-content\/uploads\/48-1f47407.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"378\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;73,31\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/\",\"name\":\"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/48-1f47407.jpg\",\"datePublished\":\"2023-06-11T11:59:48+00:00\",\"dateModified\":\"2026-08-10T07:41:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/48-1f47407.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/48-1f47407.jpg\",\"width\":378,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/producten\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verlichting\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/product-categorie\\\/verlichting-led-verlichting\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Werklampen\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/product-categorie\\\/verlichting-led-verlichting\\\/werklampen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"LED\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/product-categorie\\\/verlichting-led-verlichting\\\/werklampen\\\/led\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"name\":\"United Driveline Systems\",\"description\":\"United Driveline Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\"},\"alternateName\":\"UDS Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uds-parts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\",\"name\":\"United Driveline Systems b.v.\",\"alternateName\":\"UDS Parts\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"width\":803,\"height\":342,\"caption\":\"United Driveline Systems b.v.\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/uds_parts\\\/\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/united-driveline-systems-bv\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Wesem\" \/>\n<meta property=\"product:price:amount\" content=\"73.31\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"48-1F47407\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/","og_locale":"de_DE","og_type":"article","og_title":"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts","og_description":"Afdichtingsklasse IP67-IP69K","og_url":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/","og_site_name":"UDS Parts","article_modified_time":"2026-08-10T07:41:44+00:00","og_image":[{"width":378,"height":378,"url":"https:\/\/uds-parts.com\/wp-content\/uploads\/48-1f47407.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;73,31","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/","url":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/","name":"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting - UDS Parts","isPartOf":{"@id":"https:\/\/uds-parts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/#primaryimage"},"image":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/#primaryimage"},"thumbnailUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/48-1f47407.jpg","datePublished":"2023-06-11T11:59:48+00:00","dateModified":"2026-08-10T07:41:44+00:00","breadcrumb":{"@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/#primaryimage","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/48-1f47407.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/48-1f47407.jpg","width":378,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/uds-parts.com\/producten\/verlichting-led-verlichting\/werklampen\/led\/led-werklamp-vierkant-1500lm-12v-24v-met-deutsch-aansluiting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uds-parts.com\/de\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/uds-parts.com\/de\/webshop\/"},{"@type":"ListItem","position":3,"name":"Verlichting","item":"https:\/\/uds-parts.com\/product-categorie\/verlichting-led-verlichting\/"},{"@type":"ListItem","position":4,"name":"Werklampen","item":"https:\/\/uds-parts.com\/product-categorie\/verlichting-led-verlichting\/werklampen\/"},{"@type":"ListItem","position":5,"name":"LED","item":"https:\/\/uds-parts.com\/product-categorie\/verlichting-led-verlichting\/werklampen\/led\/"},{"@type":"ListItem","position":6,"name":"LED werklamp vierkant | 1500Lm | 12V-24V |met Deutsch aansluiting"}]},{"@type":"WebSite","@id":"https:\/\/uds-parts.com\/#website","url":"https:\/\/uds-parts.com\/","name":"United Driveline Systems","description":"United Driveline Systems","publisher":{"@id":"https:\/\/uds-parts.com\/#organization"},"alternateName":"UDS Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uds-parts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/uds-parts.com\/#organization","name":"United Driveline Systems b.v.","alternateName":"UDS Parts","url":"https:\/\/uds-parts.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","width":803,"height":342,"caption":"United Driveline Systems b.v."},"image":{"@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/uds_parts\/","https:\/\/nl.linkedin.com\/company\/united-driveline-systems-bv"]}]},"product_brand":"Wesem","product_price_amount":"73.31","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"48-1F47407","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product\/30301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media\/30283"}],"wp:attachment":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media?parent=30301"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_brand?post=30301"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_cat?post=30301"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_tag?post=30301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}