{"id":27557,"date":"2019-12-05T12:27:17","date_gmt":"2019-12-05T14:50:57","guid":{"rendered":"https:\/\/www.uds-parts.com\/producten\/unkategorisiert\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/"},"modified":"2019-12-17T15:52:42","modified_gmt":"2019-12-17T15:52:42","slug":"zahnriemen-zahn-keilriemen-bx39-uds-1033mm","status":"publish","type":"product","link":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/","title":{"rendered":"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":12576,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false},"product_brand":[],"product_cat":[9708,9716,11126],"product_tag":[],"class_list":["post-27557","product","type-product","status-publish","has-post-thumbnail","product_cat-diverse-antriebstechnik","product_cat-keilriemen-und-zahnkeilriemen","product_cat-uncategorized-de","pa_merk-uds-de","pa_type-2-bx-de","pa_verkoop-eenheid-stuk-de","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/\" \/>\n<meta property=\"og:site_name\" content=\"UDS Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-17T15:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uds-parts.com\/wp-content\/uploads\/11-V-snaar-BX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"378\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;32,76\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/\",\"name\":\"Zahnriemen \\\/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/11-V-snaar-BX.jpg\",\"datePublished\":\"2019-12-05T14:50:57+00:00\",\"dateModified\":\"2019-12-17T15:52:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/11-V-snaar-BX.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/11-V-snaar-BX.jpg\",\"width\":378,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diverse Antriebstechnik\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/produkt-kategorie\\\/diverse-antriebstechnik\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Keilriemen und Zahnkeilriemen\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/produkt-kategorie\\\/diverse-antriebstechnik\\\/keilriemen-und-zahnkeilriemen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Zahnriemen \\\/ Zahn Keilriemen BX39 UDS 1033mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"name\":\"United Driveline Systems\",\"description\":\"United Driveline Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\"},\"alternateName\":\"UDS Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uds-parts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\",\"name\":\"United Driveline Systems b.v.\",\"alternateName\":\"UDS Parts\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"width\":803,\"height\":342,\"caption\":\"United Driveline Systems b.v.\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/uds_parts\\\/\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/united-driveline-systems-bv\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"UDS\" \/>\n<meta property=\"product:price:amount\" content=\"32.76\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"19-64324\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/","og_locale":"de_DE","og_type":"article","og_title":"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts","og_url":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/","og_site_name":"UDS Parts","article_modified_time":"2019-12-17T15:52:42+00:00","og_image":[{"width":378,"height":378,"url":"https:\/\/uds-parts.com\/wp-content\/uploads\/11-V-snaar-BX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;32,76","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/","url":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/","name":"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm - UDS Parts","isPartOf":{"@id":"https:\/\/uds-parts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/#primaryimage"},"image":{"@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/#primaryimage"},"thumbnailUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/11-V-snaar-BX.jpg","datePublished":"2019-12-05T14:50:57+00:00","dateModified":"2019-12-17T15:52:42+00:00","breadcrumb":{"@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/#primaryimage","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/11-V-snaar-BX.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/11-V-snaar-BX.jpg","width":378,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/uds-parts.com\/de\/producten\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/zahnriemen-zahn-keilriemen-bx39-uds-1033mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uds-parts.com\/de\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/uds-parts.com\/de\/webshop\/"},{"@type":"ListItem","position":3,"name":"Diverse Antriebstechnik","item":"https:\/\/uds-parts.com\/de\/produkt-kategorie\/diverse-antriebstechnik\/"},{"@type":"ListItem","position":4,"name":"Keilriemen und Zahnkeilriemen","item":"https:\/\/uds-parts.com\/de\/produkt-kategorie\/diverse-antriebstechnik\/keilriemen-und-zahnkeilriemen\/"},{"@type":"ListItem","position":5,"name":"Zahnriemen \/ Zahn Keilriemen BX39 UDS 1033mm"}]},{"@type":"WebSite","@id":"https:\/\/uds-parts.com\/#website","url":"https:\/\/uds-parts.com\/","name":"United Driveline Systems","description":"United Driveline Systems","publisher":{"@id":"https:\/\/uds-parts.com\/#organization"},"alternateName":"UDS Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uds-parts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/uds-parts.com\/#organization","name":"United Driveline Systems b.v.","alternateName":"UDS Parts","url":"https:\/\/uds-parts.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","width":803,"height":342,"caption":"United Driveline Systems b.v."},"image":{"@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/uds_parts\/","https:\/\/nl.linkedin.com\/company\/united-driveline-systems-bv"]}]},"product_brand":"UDS","product_price_amount":"32.76","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"19-64324","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product\/27557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media\/12576"}],"wp:attachment":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media?parent=27557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_brand?post=27557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_cat?post=27557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_tag?post=27557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}