{"id":26376,"date":"2019-12-05T12:02:15","date_gmt":"2019-12-05T14:04:50","guid":{"rendered":"https:\/\/www.uds-parts.com\/producten\/unkategorisiert\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/"},"modified":"2019-12-17T15:26:51","modified_gmt":"2019-12-17T15:26:51","slug":"rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube","status":"publish","type":"product","link":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/","title":{"rendered":"R\u00fcckleuchte  M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":52702,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false},"product_brand":[],"product_cat":[9792,9793,11126],"product_tag":[],"class_list":["post-26376","product","type-product","status-publish","has-post-thumbnail","product_cat-beleuchtung","product_cat-ruckleuchte","product_cat-uncategorized-de","pa_maat-152mm-de","pa_merk-sanube-de","pa_type-2-led-de","pa_verkoop-eenheid-stuk-de","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/\" \/>\n<meta property=\"og:site_name\" content=\"UDS Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-17T15:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uds-parts.com\/wp-content\/uploads\/m\u00fcnchen-led-12v-kb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"245\" \/>\n\t<meta property=\"og:image:height\" content=\"171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;153,38\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"bei Nachbestellung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/\",\"name\":\"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/Sanube-munchen-LED-12V-KB.jpg\",\"datePublished\":\"2019-12-05T14:04:50+00:00\",\"dateModified\":\"2019-12-17T15:26:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/Sanube-munchen-LED-12V-KB.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/Sanube-munchen-LED-12V-KB.jpg\",\"width\":378,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/producten\\\/beleuchtung\\\/ruckleuchte\\\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beleuchtung\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/produkt-kategorie\\\/beleuchtung\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R\u00fcckleuchte\",\"item\":\"https:\\\/\\\/uds-parts.com\\\/de\\\/produkt-kategorie\\\/beleuchtung\\\/ruckleuchte\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#website\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"name\":\"United Driveline Systems\",\"description\":\"United Driveline Systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\"},\"alternateName\":\"UDS Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uds-parts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#organization\",\"name\":\"United Driveline Systems b.v.\",\"alternateName\":\"UDS Parts\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uds-parts.com\\\/wp-content\\\/uploads\\\/UDS-Logo-1.jpg\",\"width\":803,\"height\":342,\"caption\":\"United Driveline Systems b.v.\"},\"image\":{\"@id\":\"https:\\\/\\\/uds-parts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/uds_parts\\\/\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/united-driveline-systems-bv\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"SANUBE\" \/>\n<meta property=\"product:price:amount\" content=\"153.38\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"5H3187-055\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts","og_url":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/","og_site_name":"UDS Parts","article_modified_time":"2019-12-17T15:26:51+00:00","og_image":[{"width":245,"height":171,"url":"https:\/\/uds-parts.com\/wp-content\/uploads\/m\u00fcnchen-led-12v-kb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;153,38","Verf\u00fcgbarkeit":"bei Nachbestellung"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/","url":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/","name":"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube - UDS Parts","isPartOf":{"@id":"https:\/\/uds-parts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/#primaryimage"},"image":{"@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/#primaryimage"},"thumbnailUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/Sanube-munchen-LED-12V-KB.jpg","datePublished":"2019-12-05T14:04:50+00:00","dateModified":"2019-12-17T15:26:51+00:00","breadcrumb":{"@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/#primaryimage","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/Sanube-munchen-LED-12V-KB.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/Sanube-munchen-LED-12V-KB.jpg","width":378,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/uds-parts.com\/de\/producten\/beleuchtung\/ruckleuchte\/rueckleuchte-muenchen-voellig-led-rechts-12v-5-funktionen-mit-integrierter-blinker-7-polige-anschluss-sanube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uds-parts.com\/de\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/uds-parts.com\/de\/webshop\/"},{"@type":"ListItem","position":3,"name":"Beleuchtung","item":"https:\/\/uds-parts.com\/de\/produkt-kategorie\/beleuchtung\/"},{"@type":"ListItem","position":4,"name":"R\u00fcckleuchte","item":"https:\/\/uds-parts.com\/de\/produkt-kategorie\/beleuchtung\/ruckleuchte\/"},{"@type":"ListItem","position":5,"name":"R\u00fcckleuchte M\u00fcnchen v\u00f6llig LED Rechts |12V | 5 Funktionen | mit Integrierter Blinker | 7-polige Anschluss Sanube"}]},{"@type":"WebSite","@id":"https:\/\/uds-parts.com\/#website","url":"https:\/\/uds-parts.com\/","name":"United Driveline Systems","description":"United Driveline Systems","publisher":{"@id":"https:\/\/uds-parts.com\/#organization"},"alternateName":"UDS Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uds-parts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/uds-parts.com\/#organization","name":"United Driveline Systems b.v.","alternateName":"UDS Parts","url":"https:\/\/uds-parts.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/","url":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","contentUrl":"https:\/\/uds-parts.com\/wp-content\/uploads\/UDS-Logo-1.jpg","width":803,"height":342,"caption":"United Driveline Systems b.v."},"image":{"@id":"https:\/\/uds-parts.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/uds_parts\/","https:\/\/nl.linkedin.com\/company\/united-driveline-systems-bv"]}]},"product_brand":"SANUBE","product_price_amount":"153.38","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"5H3187-055","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product\/26376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media\/52702"}],"wp:attachment":[{"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/media?parent=26376"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_brand?post=26376"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_cat?post=26376"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/uds-parts.com\/de\/wp-json\/wp\/v2\/product_tag?post=26376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}